{"id":17450,"date":"2025-12-11T11:43:43","date_gmt":"2025-12-11T11:43:43","guid":{"rendered":"https:\/\/winmallspa.com\/?post_type=product&#038;p=17450"},"modified":"2025-12-11T11:44:11","modified_gmt":"2025-12-11T11:44:11","slug":"943-stone","status":"publish","type":"product","link":"https:\/\/winmallspa.com\/zh\/prodotto\/943-stone\/","title":{"rendered":"943 Stone"},"content":{"rendered":"<div class=\"elementor-element elementor-element-b8db09a elementor-widget elementor-widget-text-editor\" data-id=\"b8db09a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container mp-label\"><strong>DESCRIZIONE:<\/strong><\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-f4e3301 elementor-widget elementor-widget-text-editor\" data-id=\"f4e3301\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">Pratico e capiente il dispenser sapone a riempimento 943 con azionamento a leva garantisce un\u2019azione igienizzante pratica e sicura. Comprende kit di montaggio. Nelle versioni Carbon, Stone, Sand e Titanium viene utilizzata plastica riciclata pre e post-consumo.<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-fd031c6 elementor-widget elementor-widget-text-editor\" data-id=\"fd031c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container mp-label\"><strong>INFO TECNICHE:<\/strong><\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-89d0078 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"89d0078\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n<div class=\"elementor-widget-container\">\n<ul class=\"elementor-icon-list-items\">\n<li class=\"elementor-icon-list-item\"><i class=\"fas fa-check-double\" aria-hidden=\"true\"><\/i><span class=\"elementor-icon-list-text\"><strong>Compatibile con:<\/strong>\u00a0Qualsiasi sapone detergente liquido<\/span><\/li>\n<li class=\"elementor-icon-list-item\"><i class=\"fas fa-check-double\" aria-hidden=\"true\"><\/i><span class=\"elementor-icon-list-text\"><strong>Modalit\u00e0 di fissaggio:<\/strong>\u00a0Viti e tasselli<\/span><\/li>\n<li class=\"elementor-icon-list-item\"><i class=\"fas fa-check-double\" aria-hidden=\"true\"><\/i><span class=\"elementor-icon-list-text\"><strong>Chiusura:<\/strong>\u00a0A scatto, apertura con chiave<\/span><\/li>\n<li class=\"elementor-icon-list-item\"><i class=\"fas fa-check-double\" aria-hidden=\"true\"><\/i><span class=\"elementor-icon-list-text\"><strong>Altezza di montaggio:<\/strong>\u00a090-120 cm<\/span><\/li>\n<li class=\"elementor-icon-list-item\"><i class=\"fas fa-check-double\" aria-hidden=\"true\"><\/i><span class=\"elementor-icon-list-text\"><strong>Capacit\u00e0:<\/strong>\u00a01 L<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"elementor-element elementor-element-0d3b36d elementor-hidden-mobile elementor-widget elementor-widget-shortcode\" data-id=\"0d3b36d\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-shortcode\">\n<h1 class=\"product_title\">DISPENSER SAPONE HOSPITAL- 1 L<\/h1>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-75926ea elementor-widget elementor-widget-woocommerce-product-short-description\" data-id=\"75926ea\" data-element_type=\"widget\" data-widget_type=\"woocommerce-product-short-description.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"woocommerce-product-details__short-description\">\n<p>HOSPITAL SKIN SOAP<br \/>\nDispenser sapone liquido a riempimento<br \/>\nCon leva a gomito<br \/>\nStampa frontale per una comprensione immediata dell\u2019utilizzo corretto<br \/>\nLente trasparente per controllare lo stato di riempimento<br \/>\nCapacit\u00e0: 1 L<br \/>\nApertura con chiave Mar Plast (inclusa), chiusura a scatto<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"featured_media":17421,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[252],"product_tag":[],"class_list":{"0":"post-17450","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dispenser-sapone-a-riempimento","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>943 Stone - WINMALL SPA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/winmallspa.com\/zh\/prodotto\/943-stone\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"943 Stone - WINMALL SPA\" \/>\n<meta property=\"og:description\" content=\"DISPENSER SAPONE HOSPITAL- 1 L        HOSPITAL SKIN SOAP Dispenser sapone liquido a riempimento Con leva a gomito Stampa frontale per una comprensione immediata dell\u2019utilizzo corretto Lente trasparente per controllare lo stato di riempimento Capacit\u00e0: 1 L Apertura con chiave Mar Plast (inclusa), chiusura a scatto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/winmallspa.com\/zh\/prodotto\/943-stone\/\" \/>\n<meta property=\"og:site_name\" content=\"WINMALL SPA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-11T11:44:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/12\/A94301PO_943-stone_dispenser-sapone-a-riempimento_marplast_1-300x300-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/943-stone\\\/\",\"url\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/943-stone\\\/\",\"name\":\"943 Stone - WINMALL SPA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/943-stone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/943-stone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/winmallspa.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/A94301PO_943-stone_dispenser-sapone-a-riempimento_marplast_1-300x300-1.jpg\",\"datePublished\":\"2025-12-11T11:43:43+00:00\",\"dateModified\":\"2025-12-11T11:44:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/943-stone\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/943-stone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/943-stone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/winmallspa.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/A94301PO_943-stone_dispenser-sapone-a-riempimento_marplast_1-300x300-1.jpg\",\"contentUrl\":\"https:\\\/\\\/winmallspa.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/A94301PO_943-stone_dispenser-sapone-a-riempimento_marplast_1-300x300-1.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/943-stone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/winmallspa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/winmallspa.com\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"943 Stone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#website\",\"url\":\"https:\\\/\\\/winmallspa.com\\\/\",\"name\":\"winmallspa.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/winmallspa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#organization\",\"name\":\"winmallspa.com\",\"url\":\"https:\\\/\\\/winmallspa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/winmallspa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cta-vendorsys-logo.png\",\"contentUrl\":\"https:\\\/\\\/winmallspa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cta-vendorsys-logo.png\",\"width\":225,\"height\":225,\"caption\":\"winmallspa.com\"},\"image\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"943 Stone - WINMALL SPA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/winmallspa.com\/zh\/prodotto\/943-stone\/","og_locale":"zh_CN","og_type":"article","og_title":"943 Stone - WINMALL SPA","og_description":"DISPENSER SAPONE HOSPITAL- 1 L        HOSPITAL SKIN SOAP Dispenser sapone liquido a riempimento Con leva a gomito Stampa frontale per una comprensione immediata dell\u2019utilizzo corretto Lente trasparente per controllare lo stato di riempimento Capacit\u00e0: 1 L Apertura con chiave Mar Plast (inclusa), chiusura a scatto","og_url":"https:\/\/winmallspa.com\/zh\/prodotto\/943-stone\/","og_site_name":"WINMALL SPA","article_modified_time":"2025-12-11T11:44:11+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/12\/A94301PO_943-stone_dispenser-sapone-a-riempimento_marplast_1-300x300-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/winmallspa.com\/prodotto\/943-stone\/","url":"https:\/\/winmallspa.com\/prodotto\/943-stone\/","name":"943 Stone - WINMALL SPA","isPartOf":{"@id":"https:\/\/winmallspa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/winmallspa.com\/prodotto\/943-stone\/#primaryimage"},"image":{"@id":"https:\/\/winmallspa.com\/prodotto\/943-stone\/#primaryimage"},"thumbnailUrl":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/12\/A94301PO_943-stone_dispenser-sapone-a-riempimento_marplast_1-300x300-1.jpg","datePublished":"2025-12-11T11:43:43+00:00","dateModified":"2025-12-11T11:44:11+00:00","breadcrumb":{"@id":"https:\/\/winmallspa.com\/prodotto\/943-stone\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/winmallspa.com\/prodotto\/943-stone\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/winmallspa.com\/prodotto\/943-stone\/#primaryimage","url":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/12\/A94301PO_943-stone_dispenser-sapone-a-riempimento_marplast_1-300x300-1.jpg","contentUrl":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/12\/A94301PO_943-stone_dispenser-sapone-a-riempimento_marplast_1-300x300-1.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/winmallspa.com\/prodotto\/943-stone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/winmallspa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/winmallspa.com\/negozio\/"},{"@type":"ListItem","position":3,"name":"943 Stone"}]},{"@type":"WebSite","@id":"https:\/\/winmallspa.com\/#website","url":"https:\/\/winmallspa.com\/","name":"winmallspa.com","description":"","publisher":{"@id":"https:\/\/winmallspa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/winmallspa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/winmallspa.com\/#organization","name":"winmallspa.com","url":"https:\/\/winmallspa.com\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/winmallspa.com\/#\/schema\/logo\/image\/","url":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/07\/cta-vendorsys-logo.png","contentUrl":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/07\/cta-vendorsys-logo.png","width":225,"height":225,"caption":"winmallspa.com"},"image":{"@id":"https:\/\/winmallspa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product\/17450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/comments?post=17450"}],"version-history":[{"count":1,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product\/17450\/revisions"}],"predecessor-version":[{"id":17451,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product\/17450\/revisions\/17451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/media\/17421"}],"wp:attachment":[{"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/media?parent=17450"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product_brand?post=17450"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product_cat?post=17450"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product_tag?post=17450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}