{"id":17183,"date":"2025-12-04T07:20:33","date_gmt":"2025-12-04T07:20:33","guid":{"rendered":"https:\/\/winmallspa.com\/?post_type=product&#038;p=17183"},"modified":"2025-12-08T07:45:29","modified_gmt":"2025-12-08T07:45:29","slug":"blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2","status":"publish","type":"product","link":"https:\/\/winmallspa.com\/zh\/prodotto\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\/","title":{"rendered":"Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Accessori compatibili HY35<\/p>\n<p>Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09<\/p>","protected":false},"featured_media":17257,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[249],"product_tag":[],"class_list":{"0":"post-17183","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessori-compatibili-hy35","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09 - WINMALL SPA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/winmallspa.com\/zh\/prodotto\/blocchi-di-cingoli-in-gomma\uff08-enecessaria-la-prenotazione\uff09-2\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09 - WINMALL SPA\" \/>\n<meta property=\"og:description\" content=\"Accessori compatibili HY35  Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09\" \/>\n<meta property=\"og:url\" content=\"https:\/\/winmallspa.com\/zh\/prodotto\/blocchi-di-cingoli-in-gomma\uff08-enecessaria-la-prenotazione\uff09-2\/\" \/>\n<meta property=\"og:site_name\" content=\"WINMALL SPA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-08T07:45:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/12\/33.png\" \/>\n\t<meta property=\"og:image:width\" content=\"964\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\\\/\",\"url\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\\\/\",\"name\":\"Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09 - WINMALL SPA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/winmallspa.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/33.png\",\"datePublished\":\"2025-12-04T07:20:33+00:00\",\"dateModified\":\"2025-12-08T07:45:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/winmallspa.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/33.png\",\"contentUrl\":\"https:\\\/\\\/winmallspa.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/33.png\",\"width\":964,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/prodotto\\\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/winmallspa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/winmallspa.com\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#website\",\"url\":\"https:\\\/\\\/winmallspa.com\\\/\",\"name\":\"winmallspa.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/winmallspa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#organization\",\"name\":\"winmallspa.com\",\"url\":\"https:\\\/\\\/winmallspa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/winmallspa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cta-vendorsys-logo.png\",\"contentUrl\":\"https:\\\/\\\/winmallspa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cta-vendorsys-logo.png\",\"width\":225,\"height\":225,\"caption\":\"winmallspa.com\"},\"image\":{\"@id\":\"https:\\\/\\\/winmallspa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09 - WINMALL SPA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/winmallspa.com\/zh\/prodotto\/blocchi-di-cingoli-in-gomma\uff08-enecessaria-la-prenotazione\uff09-2\/","og_locale":"zh_CN","og_type":"article","og_title":"Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09 - WINMALL SPA","og_description":"Accessori compatibili HY35  Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09","og_url":"https:\/\/winmallspa.com\/zh\/prodotto\/blocchi-di-cingoli-in-gomma\uff08-enecessaria-la-prenotazione\uff09-2\/","og_site_name":"WINMALL SPA","article_modified_time":"2025-12-08T07:45:29+00:00","og_image":[{"width":964,"height":683,"url":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/12\/33.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/winmallspa.com\/prodotto\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\/","url":"https:\/\/winmallspa.com\/prodotto\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\/","name":"Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09 - WINMALL SPA","isPartOf":{"@id":"https:\/\/winmallspa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/winmallspa.com\/prodotto\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\/#primaryimage"},"image":{"@id":"https:\/\/winmallspa.com\/prodotto\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\/#primaryimage"},"thumbnailUrl":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/12\/33.png","datePublished":"2025-12-04T07:20:33+00:00","dateModified":"2025-12-08T07:45:29+00:00","breadcrumb":{"@id":"https:\/\/winmallspa.com\/prodotto\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/winmallspa.com\/prodotto\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/winmallspa.com\/prodotto\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\/#primaryimage","url":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/12\/33.png","contentUrl":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/12\/33.png","width":964,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/winmallspa.com\/prodotto\/blocchi-di-cingoli-in-gomma%ef%bc%88-enecessaria-la-prenotazione%ef%bc%89-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/winmallspa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/winmallspa.com\/negozio\/"},{"@type":"ListItem","position":3,"name":"Blocchi di cingoli in gomma\uff08 \u00c8necessaria la prenotazione\uff09"}]},{"@type":"WebSite","@id":"https:\/\/winmallspa.com\/#website","url":"https:\/\/winmallspa.com\/","name":"winmallspa.com","description":"","publisher":{"@id":"https:\/\/winmallspa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/winmallspa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/winmallspa.com\/#organization","name":"winmallspa.com","url":"https:\/\/winmallspa.com\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/winmallspa.com\/#\/schema\/logo\/image\/","url":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/07\/cta-vendorsys-logo.png","contentUrl":"https:\/\/winmallspa.com\/wp-content\/uploads\/2025\/07\/cta-vendorsys-logo.png","width":225,"height":225,"caption":"winmallspa.com"},"image":{"@id":"https:\/\/winmallspa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product\/17183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/comments?post=17183"}],"version-history":[{"count":1,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product\/17183\/revisions"}],"predecessor-version":[{"id":17184,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product\/17183\/revisions\/17184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/media\/17257"}],"wp:attachment":[{"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/media?parent=17183"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product_brand?post=17183"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product_cat?post=17183"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/winmallspa.com\/zh\/wp-json\/wp\/v2\/product_tag?post=17183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}